{"id":993,"date":"2025-04-30T16:18:58","date_gmt":"2025-04-30T16:18:58","guid":{"rendered":"https:\/\/acervolegislativo.com.br\/document\/lei-municipal-no-350-2009-institui-no-ambito-do-municipio-de-canitar-nos-termos-da-lei-federal-no-10-520-a-modalidade-pregao\/"},"modified":"2025-04-30T16:40:33","modified_gmt":"2025-04-30T16:40:33","slug":"lei-municipal-no-350-2009-institui-no-ambito-do-municipio-de-canitar-nos-termos-da-lei-federal-no-10-520-a-modalidade-pregao","status":"publish","type":"dlp_document","link":"https:\/\/acervolegislativo.com.br\/pt_br\/document\/lei-municipal-no-350-2009-institui-no-ambito-do-municipio-de-canitar-nos-termos-da-lei-federal-no-10-520-a-modalidade-pregao\/","title":{"rendered":"Lei Municipal n\u00ba 350 2009   Institui, no \u00e2mbito do munic\u00edpio de Canitar, nos termos da Lei Federal n\u00ba 10.520, a modalidade Preg\u00e3o."},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":994,"template":"","doc_categories":[7],"doc_tags":[33],"doc_author":[],"file_type":[11],"class_list":["post-993","dlp_document","type-dlp_document","status-publish","has-post-thumbnail","hentry","doc_categories-leis-municipais","doc_tags-33","entry","has-media"],"download_url":"https:\/\/acervolegislativo.com.br\/wp-content\/uploads\/2025\/04\/Lei-Municipal-no-350-2009-Institui-no-ambito-do-municipio-de-Canitar-nos-termos-da-Lei-Federal-no-10.520-a-modalidade-Pregao.pdf","file_size":"533 KB","filename":"Lei-Municipal-no-350-2009-Institui-no-ambito-do-municipio-de-Canitar-nos-termos-da-Lei-Federal-no-10.520-a-modalidade-Pregao.pdf","download_count":"","version_history":[],"_links":{"self":[{"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/dlp_document\/993","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/dlp_document"}],"about":[{"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/types\/dlp_document"}],"author":[{"embeddable":true,"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/users\/2"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/media\/994"}],"wp:attachment":[{"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/media?parent=993"}],"wp:term":[{"taxonomy":"doc_categories","embeddable":true,"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/doc_categories?post=993"},{"taxonomy":"doc_tags","embeddable":true,"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/doc_tags?post=993"},{"taxonomy":"doc_author","embeddable":true,"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/doc_author?post=993"},{"taxonomy":"file_type","embeddable":true,"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/file_type?post=993"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}