{"id":731,"date":"2025-04-30T15:48:26","date_gmt":"2025-04-30T15:48:26","guid":{"rendered":"https:\/\/acervolegislativo.com.br\/document\/lei-municipal-no-253-2005-autoriza-a-prefeitura-municipal-de-canitar-celebrar-convenio-com-a-funasa\/"},"modified":"2025-04-30T15:50:28","modified_gmt":"2025-04-30T15:50:28","slug":"lei-municipal-no-253-2005-autoriza-a-prefeitura-municipal-de-canitar-celebrar-convenio-com-a-funasa","status":"publish","type":"dlp_document","link":"https:\/\/acervolegislativo.com.br\/pt_br\/document\/lei-municipal-no-253-2005-autoriza-a-prefeitura-municipal-de-canitar-celebrar-convenio-com-a-funasa\/","title":{"rendered":"Lei Municipal n\u00ba 253 2005   Autoriza a Prefeitura Municipal de Canitar celebrar conv\u00eanio com a FUNASA."},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":732,"template":"","doc_categories":[7],"doc_tags":[29],"doc_author":[],"file_type":[11],"class_list":["post-731","dlp_document","type-dlp_document","status-publish","has-post-thumbnail","hentry","doc_categories-leis-municipais","doc_tags-29","entry","has-media"],"download_url":"https:\/\/acervolegislativo.com.br\/wp-content\/uploads\/2025\/04\/Lei-Municipal-no-253-2005-Autoriza-a-Prefeitura-Municipal-de-Canitar-celebrar-convenio-com-a-FUNASA.pdf","file_size":"510 KB","filename":"Lei-Municipal-no-253-2005-Autoriza-a-Prefeitura-Municipal-de-Canitar-celebrar-convenio-com-a-FUNASA.pdf","download_count":"","version_history":[],"_links":{"self":[{"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/dlp_document\/731","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/dlp_document"}],"about":[{"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/types\/dlp_document"}],"author":[{"embeddable":true,"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/users\/2"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/media\/732"}],"wp:attachment":[{"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/media?parent=731"}],"wp:term":[{"taxonomy":"doc_categories","embeddable":true,"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/doc_categories?post=731"},{"taxonomy":"doc_tags","embeddable":true,"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/doc_tags?post=731"},{"taxonomy":"doc_author","embeddable":true,"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/doc_author?post=731"},{"taxonomy":"file_type","embeddable":true,"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/file_type?post=731"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}