{"id":72,"date":"2025-04-18T20:00:48","date_gmt":"2025-04-18T20:00:48","guid":{"rendered":"https:\/\/acervolegislativo.com.br\/document\/lei-municipal-no-16-1993-da-denominacao-de-anibal-lopes-da-fonseca-a-atual-alameda-ii-da-vila-manuel-cabette\/"},"modified":"2025-04-18T20:25:26","modified_gmt":"2025-04-18T20:25:26","slug":"lei-municipal-no-16-1993-da-denominacao-de-anibal-lopes-da-fonseca-a-atual-alameda-ii-da-vila-manuel-cabette","status":"publish","type":"dlp_document","link":"https:\/\/acervolegislativo.com.br\/pt_br\/document\/lei-municipal-no-16-1993-da-denominacao-de-anibal-lopes-da-fonseca-a-atual-alameda-ii-da-vila-manuel-cabette\/","title":{"rendered":"Lei Municipal n\u00ba 16 1993   D\u00e1 denomina\u00e7\u00e3o de Anibal Lopes da Fonseca \u00e0 atual Alameda II da Vila Manuel Cabette."},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":73,"template":"","doc_categories":[7],"doc_tags":[13],"doc_author":[],"file_type":[11],"class_list":["post-72","dlp_document","type-dlp_document","status-publish","has-post-thumbnail","hentry","doc_categories-leis-municipais","doc_tags-13","entry","has-media"],"download_url":"https:\/\/acervolegislativo.com.br\/wp-content\/uploads\/2025\/04\/Lei-Municipal-no-16-1993-Da-denominacao-de-Anibal-Lopes-da-Fonseca-a-atual-Alameda-II-da-Vila-Manuel-Cabette.pdf","file_size":"243 KB","filename":"Lei-Municipal-no-16-1993-Da-denominacao-de-Anibal-Lopes-da-Fonseca-a-atual-Alameda-II-da-Vila-Manuel-Cabette.pdf","download_count":"","version_history":[],"_links":{"self":[{"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/dlp_document\/72","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/dlp_document"}],"about":[{"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/types\/dlp_document"}],"author":[{"embeddable":true,"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/users\/1"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/media\/73"}],"wp:attachment":[{"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/media?parent=72"}],"wp:term":[{"taxonomy":"doc_categories","embeddable":true,"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/doc_categories?post=72"},{"taxonomy":"doc_tags","embeddable":true,"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/doc_tags?post=72"},{"taxonomy":"doc_author","embeddable":true,"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/doc_author?post=72"},{"taxonomy":"file_type","embeddable":true,"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/file_type?post=72"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}