{"id":431,"date":"2025-04-30T14:53:28","date_gmt":"2025-04-30T14:53:28","guid":{"rendered":"https:\/\/acervolegislativo.com.br\/document\/lei-municipal-no-121-1998-autoriza-o-poder-executivo-de-canitar-a-firmar-acordo-de-parcelamento-de-divida-para-com-o-fgts\/"},"modified":"2025-04-30T14:56:30","modified_gmt":"2025-04-30T14:56:30","slug":"lei-municipal-no-121-1998-autoriza-o-poder-executivo-de-canitar-a-firmar-acordo-de-parcelamento-de-divida-para-com-o-fgts","status":"publish","type":"dlp_document","link":"https:\/\/acervolegislativo.com.br\/pt_br\/document\/lei-municipal-no-121-1998-autoriza-o-poder-executivo-de-canitar-a-firmar-acordo-de-parcelamento-de-divida-para-com-o-fgts\/","title":{"rendered":"Lei Municipal n\u00ba 121 1998   Autoriza o Poder Executivo de Canitar a firmar acordo de parcelamento de d\u00edvida para com o FGTS."},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":432,"template":"","doc_categories":[7],"doc_tags":[22],"doc_author":[],"file_type":[11],"class_list":["post-431","dlp_document","type-dlp_document","status-publish","has-post-thumbnail","hentry","doc_categories-leis-municipais","doc_tags-22","entry","has-media"],"download_url":"https:\/\/acervolegislativo.com.br\/wp-content\/uploads\/2025\/04\/Lei-Municipal-no-121-1998-Autoriza-o-Poder-Executivo-de-Canitar-a-firmar-acordo-de-parcelamento-de-divida-para-com-o-FGTS.pdf","file_size":"351 KB","filename":"Lei-Municipal-no-121-1998-Autoriza-o-Poder-Executivo-de-Canitar-a-firmar-acordo-de-parcelamento-de-divida-para-com-o-FGTS.pdf","download_count":"","version_history":[],"_links":{"self":[{"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/dlp_document\/431","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/dlp_document"}],"about":[{"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/types\/dlp_document"}],"author":[{"embeddable":true,"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/users\/2"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/media\/432"}],"wp:attachment":[{"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/media?parent=431"}],"wp:term":[{"taxonomy":"doc_categories","embeddable":true,"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/doc_categories?post=431"},{"taxonomy":"doc_tags","embeddable":true,"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/doc_tags?post=431"},{"taxonomy":"doc_author","embeddable":true,"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/doc_author?post=431"},{"taxonomy":"file_type","embeddable":true,"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/file_type?post=431"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}