{"id":2485,"date":"2025-04-30T21:25:56","date_gmt":"2025-04-30T21:25:56","guid":{"rendered":"https:\/\/acervolegislativo.com.br\/document\/lei-municipal-no-07-1993-autoriza-o-executivo-municipal-a-locar-imovel-para-instalacao-da-delegacia-de-policia-de-canitar\/"},"modified":"2025-04-30T21:28:07","modified_gmt":"2025-04-30T21:28:07","slug":"lei-municipal-no-07-1993-autoriza-o-executivo-municipal-a-locar-imovel-para-instalacao-da-delegacia-de-policia-de-canitar","status":"publish","type":"dlp_document","link":"https:\/\/acervolegislativo.com.br\/pt_br\/document\/lei-municipal-no-07-1993-autoriza-o-executivo-municipal-a-locar-imovel-para-instalacao-da-delegacia-de-policia-de-canitar\/","title":{"rendered":"Lei Municipal n\u00ba 07 1993   Autoriza o Executivo Municipal a locar im\u00f3vel para instala\u00e7\u00e3o da Delegacia de Pol\u00edcia de Canitar."},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":2486,"template":"","doc_categories":[7],"doc_tags":[13],"doc_author":[],"file_type":[11],"class_list":["post-2485","dlp_document","type-dlp_document","status-publish","has-post-thumbnail","hentry","doc_categories-leis-municipais","doc_tags-13","entry","has-media"],"download_url":"https:\/\/acervolegislativo.com.br\/wp-content\/uploads\/2025\/04\/Lei-Municipal-no-07-1993-Autoriza-o-Executivo-Municipal-a-locar-imovel-para-instalacao-da-Delegacia-de-Policia-de-Canitar.pdf","file_size":"445 KB","filename":"Lei-Municipal-no-07-1993-Autoriza-o-Executivo-Municipal-a-locar-imovel-para-instalacao-da-Delegacia-de-Policia-de-Canitar.pdf","download_count":"","version_history":[],"_links":{"self":[{"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/dlp_document\/2485","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/dlp_document"}],"about":[{"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/types\/dlp_document"}],"author":[{"embeddable":true,"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/users\/2"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/media\/2486"}],"wp:attachment":[{"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/media?parent=2485"}],"wp:term":[{"taxonomy":"doc_categories","embeddable":true,"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/doc_categories?post=2485"},{"taxonomy":"doc_tags","embeddable":true,"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/doc_tags?post=2485"},{"taxonomy":"doc_author","embeddable":true,"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/doc_author?post=2485"},{"taxonomy":"file_type","embeddable":true,"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/file_type?post=2485"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}