{"id":2481,"date":"2025-04-30T21:25:51","date_gmt":"2025-04-30T21:25:51","guid":{"rendered":"https:\/\/acervolegislativo.com.br\/document\/lei-municipal-no-05-1993-autoriza-o-executivo-municipal-a-conceder-adiantamento-de-numerarios\/"},"modified":"2025-04-30T21:28:07","modified_gmt":"2025-04-30T21:28:07","slug":"lei-municipal-no-05-1993-autoriza-o-executivo-municipal-a-conceder-adiantamento-de-numerarios","status":"publish","type":"dlp_document","link":"https:\/\/acervolegislativo.com.br\/pt_br\/document\/lei-municipal-no-05-1993-autoriza-o-executivo-municipal-a-conceder-adiantamento-de-numerarios\/","title":{"rendered":"Lei Municipal n\u00ba 05 1993   Autoriza o Executivo Municipal a conceder adiantamento de numer\u00e1rios."},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":2482,"template":"","doc_categories":[7],"doc_tags":[13],"doc_author":[],"file_type":[11],"class_list":["post-2481","dlp_document","type-dlp_document","status-publish","has-post-thumbnail","hentry","doc_categories-leis-municipais","doc_tags-13","entry","has-media"],"download_url":"https:\/\/acervolegislativo.com.br\/wp-content\/uploads\/2025\/04\/Lei-Municipal-no-05-1993-Autoriza-o-Executivo-Municipal-a-conceder-adiantamento-de-numerarios.pdf","file_size":"759 KB","filename":"Lei-Municipal-no-05-1993-Autoriza-o-Executivo-Municipal-a-conceder-adiantamento-de-numerarios.pdf","download_count":"","version_history":[],"_links":{"self":[{"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/dlp_document\/2481","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/dlp_document"}],"about":[{"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/types\/dlp_document"}],"author":[{"embeddable":true,"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/users\/2"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/media\/2482"}],"wp:attachment":[{"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/media?parent=2481"}],"wp:term":[{"taxonomy":"doc_categories","embeddable":true,"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/doc_categories?post=2481"},{"taxonomy":"doc_tags","embeddable":true,"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/doc_tags?post=2481"},{"taxonomy":"doc_author","embeddable":true,"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/doc_author?post=2481"},{"taxonomy":"file_type","embeddable":true,"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/file_type?post=2481"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}