{"id":2303,"date":"2025-04-30T20:43:58","date_gmt":"2025-04-30T20:43:58","guid":{"rendered":"https:\/\/acervolegislativo.com.br\/document\/lei-municipal-no-1011-2023-autoriza-o-poder-executivo-municipal-a-receber-em-doacao-areas-de-terras-para-via-publica\/"},"modified":"2025-04-30T20:46:34","modified_gmt":"2025-04-30T20:46:34","slug":"lei-municipal-no-1011-2023-autoriza-o-poder-executivo-municipal-a-receber-em-doacao-areas-de-terras-para-via-publica","status":"publish","type":"dlp_document","link":"https:\/\/acervolegislativo.com.br\/pt_br\/document\/lei-municipal-no-1011-2023-autoriza-o-poder-executivo-municipal-a-receber-em-doacao-areas-de-terras-para-via-publica\/","title":{"rendered":"Lei Municipal n\u00ba 1011 2023   Autoriza o Poder Executivo Municipal a receber em doa\u00e7\u00e3o \u00e1reas de terras para via p\u00fablica."},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":2304,"template":"","doc_categories":[7],"doc_tags":[47],"doc_author":[],"file_type":[11],"class_list":["post-2303","dlp_document","type-dlp_document","status-publish","has-post-thumbnail","hentry","doc_categories-leis-municipais","doc_tags-47","entry","has-media"],"download_url":"https:\/\/acervolegislativo.com.br\/wp-content\/uploads\/2025\/04\/Lei-Municipal-no-1011-2023-Autoriza-o-Poder-Executivo-Municipal-a-receber-em-doacao-areas-de-terras-para-via-publica.pdf","file_size":"173 KB","filename":"Lei-Municipal-no-1011-2023-Autoriza-o-Poder-Executivo-Municipal-a-receber-em-doacao-areas-de-terras-para-via-publica.pdf","download_count":"","version_history":[],"_links":{"self":[{"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/dlp_document\/2303","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/dlp_document"}],"about":[{"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/types\/dlp_document"}],"author":[{"embeddable":true,"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/users\/2"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/media\/2304"}],"wp:attachment":[{"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/media?parent=2303"}],"wp:term":[{"taxonomy":"doc_categories","embeddable":true,"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/doc_categories?post=2303"},{"taxonomy":"doc_tags","embeddable":true,"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/doc_tags?post=2303"},{"taxonomy":"doc_author","embeddable":true,"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/doc_author?post=2303"},{"taxonomy":"file_type","embeddable":true,"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/file_type?post=2303"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}