{"id":2187,"date":"2025-04-30T20:37:31","date_gmt":"2025-04-30T20:37:31","guid":{"rendered":"https:\/\/acervolegislativo.com.br\/document\/lei-municipal-no-955-2022-altera-dispositivos-da-lei-municipal-no-337-2008-que-disciplina-o-pagamento-de-precatorios\/"},"modified":"2025-04-30T20:39:55","modified_gmt":"2025-04-30T20:39:55","slug":"lei-municipal-no-955-2022-altera-dispositivos-da-lei-municipal-no-337-2008-que-disciplina-o-pagamento-de-precatorios","status":"publish","type":"dlp_document","link":"https:\/\/acervolegislativo.com.br\/pt_br\/document\/lei-municipal-no-955-2022-altera-dispositivos-da-lei-municipal-no-337-2008-que-disciplina-o-pagamento-de-precatorios\/","title":{"rendered":"Lei Municipal n\u00ba 955 2022   Altera dispositivos da Lei Municipal n\u00ba 337 2008, que disciplina o pagamento de precat\u00f3rios."},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":2188,"template":"","doc_categories":[7],"doc_tags":[46],"doc_author":[],"file_type":[11],"class_list":["post-2187","dlp_document","type-dlp_document","status-publish","has-post-thumbnail","hentry","doc_categories-leis-municipais","doc_tags-46","entry","has-media"],"download_url":"https:\/\/acervolegislativo.com.br\/wp-content\/uploads\/2025\/04\/Lei-Municipal-no-955-2022-Altera-dispositivos-da-Lei-Municipal-no-337-2008-que-disciplina-o-pagamento-de-precatorios.pdf","file_size":"109 KB","filename":"Lei-Municipal-no-955-2022-Altera-dispositivos-da-Lei-Municipal-no-337-2008-que-disciplina-o-pagamento-de-precatorios.pdf","download_count":"4","version_history":[],"_links":{"self":[{"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/dlp_document\/2187","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/dlp_document"}],"about":[{"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/types\/dlp_document"}],"author":[{"embeddable":true,"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/users\/2"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/media\/2188"}],"wp:attachment":[{"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/media?parent=2187"}],"wp:term":[{"taxonomy":"doc_categories","embeddable":true,"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/doc_categories?post=2187"},{"taxonomy":"doc_tags","embeddable":true,"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/doc_tags?post=2187"},{"taxonomy":"doc_author","embeddable":true,"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/doc_author?post=2187"},{"taxonomy":"file_type","embeddable":true,"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/file_type?post=2187"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}