{"id":2107,"date":"2025-04-30T20:35:57","date_gmt":"2025-04-30T20:35:57","guid":{"rendered":"https:\/\/acervolegislativo.com.br\/document\/lei-municipal-no-914-2022-institui-a-criacao-do-conselho-municipal-dos-direitos-da-pessoa-com-deficiencia\/"},"modified":"2025-04-30T20:39:57","modified_gmt":"2025-04-30T20:39:57","slug":"lei-municipal-no-914-2022-institui-a-criacao-do-conselho-municipal-dos-direitos-da-pessoa-com-deficiencia","status":"publish","type":"dlp_document","link":"https:\/\/acervolegislativo.com.br\/pt_br\/document\/lei-municipal-no-914-2022-institui-a-criacao-do-conselho-municipal-dos-direitos-da-pessoa-com-deficiencia\/","title":{"rendered":"Lei Municipal n\u00ba 914 2022   Institui a cria\u00e7\u00e3o do Conselho Municipal dos direitos da Pessoa com Defici\u00eancia."},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":2108,"template":"","doc_categories":[7],"doc_tags":[46],"doc_author":[],"file_type":[11],"class_list":["post-2107","dlp_document","type-dlp_document","status-publish","has-post-thumbnail","hentry","doc_categories-leis-municipais","doc_tags-46","entry","has-media"],"download_url":"https:\/\/acervolegislativo.com.br\/wp-content\/uploads\/2025\/04\/Lei-Municipal-no-914-2022-Institui-a-criacao-do-Conselho-Municipal-dos-direitos-da-Pessoa-com-Deficiencia.pdf","file_size":"526 KB","filename":"Lei-Municipal-no-914-2022-Institui-a-criacao-do-Conselho-Municipal-dos-direitos-da-Pessoa-com-Deficiencia.pdf","download_count":"5","version_history":[],"_links":{"self":[{"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/dlp_document\/2107","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/dlp_document"}],"about":[{"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/types\/dlp_document"}],"author":[{"embeddable":true,"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/users\/2"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/media\/2108"}],"wp:attachment":[{"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/media?parent=2107"}],"wp:term":[{"taxonomy":"doc_categories","embeddable":true,"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/doc_categories?post=2107"},{"taxonomy":"doc_tags","embeddable":true,"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/doc_tags?post=2107"},{"taxonomy":"doc_author","embeddable":true,"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/doc_author?post=2107"},{"taxonomy":"file_type","embeddable":true,"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/file_type?post=2107"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}