{"id":2091,"date":"2025-04-30T20:35:34","date_gmt":"2025-04-30T20:35:34","guid":{"rendered":"https:\/\/acervolegislativo.com.br\/document\/lei-municipal-no-906-2022-dispoe-sobre-abertura-de-credito-destinados-da-base-nacional-comum-bncc-e-do-plano-nacional-de-educacao-pne\/"},"modified":"2025-04-30T20:39:58","modified_gmt":"2025-04-30T20:39:58","slug":"lei-municipal-no-906-2022-dispoe-sobre-abertura-de-credito-destinados-da-base-nacional-comum-bncc-e-do-plano-nacional-de-educacao-pne","status":"publish","type":"dlp_document","link":"https:\/\/acervolegislativo.com.br\/pt_br\/document\/lei-municipal-no-906-2022-dispoe-sobre-abertura-de-credito-destinados-da-base-nacional-comum-bncc-e-do-plano-nacional-de-educacao-pne\/","title":{"rendered":"Lei Municipal n\u00ba 906 2022   Disp\u00f5e sobre abertura de cr\u00e9dito, destinados da Base Nacional Comum (BNCC) e do Plano Nacional de Educa\u00e7\u00e3o (PNE)."},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":2092,"template":"","doc_categories":[7],"doc_tags":[46],"doc_author":[],"file_type":[11],"class_list":["post-2091","dlp_document","type-dlp_document","status-publish","has-post-thumbnail","hentry","doc_categories-leis-municipais","doc_tags-46","entry","has-media"],"download_url":"https:\/\/acervolegislativo.com.br\/wp-content\/uploads\/2025\/04\/Lei-Municipal-no-906-2022-Dispoe-sobre-abertura-de-credito-destinados-da-Base-Nacional-Comum-BNCC-e-do-Plano-Nacional-de-Educacao-PNE.pdf","file_size":"322 KB","filename":"Lei-Municipal-no-906-2022-Dispoe-sobre-abertura-de-credito-destinados-da-Base-Nacional-Comum-BNCC-e-do-Plano-Nacional-de-Educacao-PNE.pdf","download_count":"","version_history":[],"_links":{"self":[{"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/dlp_document\/2091","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/dlp_document"}],"about":[{"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/types\/dlp_document"}],"author":[{"embeddable":true,"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/users\/2"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/media\/2092"}],"wp:attachment":[{"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/media?parent=2091"}],"wp:term":[{"taxonomy":"doc_categories","embeddable":true,"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/doc_categories?post=2091"},{"taxonomy":"doc_tags","embeddable":true,"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/doc_tags?post=2091"},{"taxonomy":"doc_author","embeddable":true,"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/doc_author?post=2091"},{"taxonomy":"file_type","embeddable":true,"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/file_type?post=2091"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}