{"id":2031,"date":"2025-04-30T20:27:41","date_gmt":"2025-04-30T20:27:41","guid":{"rendered":"https:\/\/acervolegislativo.com.br\/document\/lei-municipal-no-878-2021-autoriza-o-poder-executivo-a-firmar-convenio-com-o-der-sp\/"},"modified":"2025-04-30T20:31:52","modified_gmt":"2025-04-30T20:31:52","slug":"lei-municipal-no-878-2021-autoriza-o-poder-executivo-a-firmar-convenio-com-o-der-sp","status":"publish","type":"dlp_document","link":"https:\/\/acervolegislativo.com.br\/pt_br\/document\/lei-municipal-no-878-2021-autoriza-o-poder-executivo-a-firmar-convenio-com-o-der-sp\/","title":{"rendered":"Lei Municipal n\u00ba 878 2021   Autoriza o Poder Executivo a firmar conv\u00eanio com o DER SP."},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":2032,"template":"","doc_categories":[7],"doc_tags":[45],"doc_author":[],"file_type":[11],"class_list":["post-2031","dlp_document","type-dlp_document","status-publish","has-post-thumbnail","hentry","doc_categories-leis-municipais","doc_tags-45","entry","has-media"],"download_url":"https:\/\/acervolegislativo.com.br\/wp-content\/uploads\/2025\/04\/Lei-Municipal-no-878-2021-Autoriza-o-Poder-Executivo-a-firmar-convenio-com-o-DER-SP.pdf","file_size":"96 KB","filename":"Lei-Municipal-no-878-2021-Autoriza-o-Poder-Executivo-a-firmar-convenio-com-o-DER-SP.pdf","download_count":"","version_history":[],"_links":{"self":[{"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/dlp_document\/2031","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/dlp_document"}],"about":[{"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/types\/dlp_document"}],"author":[{"embeddable":true,"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/users\/2"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/media\/2032"}],"wp:attachment":[{"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/media?parent=2031"}],"wp:term":[{"taxonomy":"doc_categories","embeddable":true,"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/doc_categories?post=2031"},{"taxonomy":"doc_tags","embeddable":true,"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/doc_tags?post=2031"},{"taxonomy":"doc_author","embeddable":true,"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/doc_author?post=2031"},{"taxonomy":"file_type","embeddable":true,"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/file_type?post=2031"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}