{"id":1815,"date":"2025-04-30T20:06:48","date_gmt":"2025-04-30T20:06:48","guid":{"rendered":"https:\/\/acervolegislativo.com.br\/document\/lei-municipal-no-781-2019-dispoe-sobre-denominacao-de-proprio-publico-casa-da-agricultura-dorival-maia\/"},"modified":"2025-04-30T20:08:23","modified_gmt":"2025-04-30T20:08:23","slug":"lei-municipal-no-781-2019-dispoe-sobre-denominacao-de-proprio-publico-casa-da-agricultura-dorival-maia","status":"publish","type":"dlp_document","link":"https:\/\/acervolegislativo.com.br\/pt_br\/document\/lei-municipal-no-781-2019-dispoe-sobre-denominacao-de-proprio-publico-casa-da-agricultura-dorival-maia\/","title":{"rendered":"Lei Municipal n\u00ba 781 2019   Disp\u00f5e sobre denomina\u00e7\u00e3o de Pr\u00f3prio P\u00fablico   Casa da Agricultura Dorival Maia."},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":1816,"template":"","doc_categories":[7],"doc_tags":[43],"doc_author":[],"file_type":[11],"class_list":["post-1815","dlp_document","type-dlp_document","status-publish","has-post-thumbnail","hentry","doc_categories-leis-municipais","doc_tags-43","entry","has-media"],"download_url":"https:\/\/acervolegislativo.com.br\/wp-content\/uploads\/2025\/04\/Lei-Municipal-no-781-2019-Dispoe-sobre-denominacao-de-Proprio-Publico-Casa-da-Agricultura-Dorival-Maia.pdf","file_size":"70 KB","filename":"Lei-Municipal-no-781-2019-Dispoe-sobre-denominacao-de-Proprio-Publico-Casa-da-Agricultura-Dorival-Maia.pdf","download_count":"","version_history":[],"_links":{"self":[{"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/dlp_document\/1815","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/dlp_document"}],"about":[{"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/types\/dlp_document"}],"author":[{"embeddable":true,"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/users\/2"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/media\/1816"}],"wp:attachment":[{"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/media?parent=1815"}],"wp:term":[{"taxonomy":"doc_categories","embeddable":true,"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/doc_categories?post=1815"},{"taxonomy":"doc_tags","embeddable":true,"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/doc_tags?post=1815"},{"taxonomy":"doc_author","embeddable":true,"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/doc_author?post=1815"},{"taxonomy":"file_type","embeddable":true,"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/file_type?post=1815"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}