{"id":1631,"date":"2025-04-30T19:46:24","date_gmt":"2025-04-30T19:46:24","guid":{"rendered":"https:\/\/acervolegislativo.com.br\/document\/lei-municipal-no-607-2016-dispoe-sobre-denominacao-de-via-publica-neuza-balbino-dos-santos\/"},"modified":"2025-04-30T19:48:55","modified_gmt":"2025-04-30T19:48:55","slug":"lei-municipal-no-607-2016-dispoe-sobre-denominacao-de-via-publica-neuza-balbino-dos-santos","status":"publish","type":"dlp_document","link":"https:\/\/acervolegislativo.com.br\/pt_br\/document\/lei-municipal-no-607-2016-dispoe-sobre-denominacao-de-via-publica-neuza-balbino-dos-santos\/","title":{"rendered":"Lei Municipal n\u00ba 607 2016   Disp\u00f5e sobre denomina\u00e7\u00e3o de via p\u00fablica   Neuza Balbino dos Santos."},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":1632,"template":"","doc_categories":[7],"doc_tags":[40],"doc_author":[],"file_type":[11],"class_list":["post-1631","dlp_document","type-dlp_document","status-publish","has-post-thumbnail","hentry","doc_categories-leis-municipais","doc_tags-40","entry","has-media"],"download_url":"https:\/\/acervolegislativo.com.br\/wp-content\/uploads\/2025\/04\/Lei-Municipal-no-607-2016-Dispoe-sobre-denominacao-de-via-publica-Neuza-Balbino-dos-Santos.pdf","file_size":"231 KB","filename":"Lei-Municipal-no-607-2016-Dispoe-sobre-denominacao-de-via-publica-Neuza-Balbino-dos-Santos.pdf","download_count":"","version_history":[],"_links":{"self":[{"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/dlp_document\/1631","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/dlp_document"}],"about":[{"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/types\/dlp_document"}],"author":[{"embeddable":true,"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/users\/2"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/media\/1632"}],"wp:attachment":[{"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/media?parent=1631"}],"wp:term":[{"taxonomy":"doc_categories","embeddable":true,"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/doc_categories?post=1631"},{"taxonomy":"doc_tags","embeddable":true,"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/doc_tags?post=1631"},{"taxonomy":"doc_author","embeddable":true,"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/doc_author?post=1631"},{"taxonomy":"file_type","embeddable":true,"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/file_type?post=1631"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}