{"id":1431,"date":"2025-04-30T17:45:47","date_gmt":"2025-04-30T17:45:47","guid":{"rendered":"https:\/\/acervolegislativo.com.br\/document\/lei-municipal-no-527-2014-autoriza-o-executivo-municipal-celebrar-termo-de-convenio-com-a-ummes\/"},"modified":"2025-04-30T17:48:26","modified_gmt":"2025-04-30T17:48:26","slug":"lei-municipal-no-527-2014-autoriza-o-executivo-municipal-celebrar-termo-de-convenio-com-a-ummes","status":"publish","type":"dlp_document","link":"https:\/\/acervolegislativo.com.br\/pt_br\/document\/lei-municipal-no-527-2014-autoriza-o-executivo-municipal-celebrar-termo-de-convenio-com-a-ummes\/","title":{"rendered":"Lei Municipal n\u00ba 527 2014   Autoriza o Executivo Municipal celebrar Termo de conv\u00eanio com a UMMES."},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":1432,"template":"","doc_categories":[7],"doc_tags":[38],"doc_author":[],"file_type":[11],"class_list":["post-1431","dlp_document","type-dlp_document","status-publish","has-post-thumbnail","hentry","doc_categories-leis-municipais","doc_tags-38","entry","has-media"],"download_url":"https:\/\/acervolegislativo.com.br\/wp-content\/uploads\/2025\/04\/Lei-Municipal-no-527-2014-Autoriza-o-Executivo-Municipal-celebrar-Termo-de-convenio-com-a-UMMES.pdf","file_size":"464 KB","filename":"Lei-Municipal-no-527-2014-Autoriza-o-Executivo-Municipal-celebrar-Termo-de-convenio-com-a-UMMES.pdf","download_count":"","version_history":[],"_links":{"self":[{"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/dlp_document\/1431","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/dlp_document"}],"about":[{"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/types\/dlp_document"}],"author":[{"embeddable":true,"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/users\/2"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/media\/1432"}],"wp:attachment":[{"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/media?parent=1431"}],"wp:term":[{"taxonomy":"doc_categories","embeddable":true,"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/doc_categories?post=1431"},{"taxonomy":"doc_tags","embeddable":true,"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/doc_tags?post=1431"},{"taxonomy":"doc_author","embeddable":true,"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/doc_author?post=1431"},{"taxonomy":"file_type","embeddable":true,"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/file_type?post=1431"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}