{"id":1305,"date":"2025-04-30T17:30:33","date_gmt":"2025-04-30T17:30:33","guid":{"rendered":"https:\/\/acervolegislativo.com.br\/document\/lei-municipal-no-480-2012-estabelece-criterios-para-viabilizacao-do-programa-minha-casa-minha-vida\/"},"modified":"2025-04-30T17:33:23","modified_gmt":"2025-04-30T17:33:23","slug":"lei-municipal-no-480-2012-estabelece-criterios-para-viabilizacao-do-programa-minha-casa-minha-vida","status":"publish","type":"dlp_document","link":"https:\/\/acervolegislativo.com.br\/pt_br\/document\/lei-municipal-no-480-2012-estabelece-criterios-para-viabilizacao-do-programa-minha-casa-minha-vida\/","title":{"rendered":"Lei Municipal n\u00ba 480 2012   Estabelece crit\u00e9rios, para viabiliza\u00e7\u00e3o do Programa Minha Casa, Minha Vida."},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":1306,"template":"","doc_categories":[7],"doc_tags":[36],"doc_author":[],"file_type":[11],"class_list":["post-1305","dlp_document","type-dlp_document","status-publish","has-post-thumbnail","hentry","doc_categories-leis-municipais","doc_tags-36","entry","has-media"],"download_url":"https:\/\/acervolegislativo.com.br\/wp-content\/uploads\/2025\/04\/Lei-Municipal-no-480-2012-Estabelece-criterios-para-viabilizacao-do-Programa-Minha-Casa-Minha-Vida.pdf","file_size":"786 KB","filename":"Lei-Municipal-no-480-2012-Estabelece-criterios-para-viabilizacao-do-Programa-Minha-Casa-Minha-Vida.pdf","download_count":"1","version_history":[],"_links":{"self":[{"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/dlp_document\/1305","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/dlp_document"}],"about":[{"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/types\/dlp_document"}],"author":[{"embeddable":true,"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/users\/2"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/media\/1306"}],"wp:attachment":[{"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/media?parent=1305"}],"wp:term":[{"taxonomy":"doc_categories","embeddable":true,"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/doc_categories?post=1305"},{"taxonomy":"doc_tags","embeddable":true,"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/doc_tags?post=1305"},{"taxonomy":"doc_author","embeddable":true,"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/doc_author?post=1305"},{"taxonomy":"file_type","embeddable":true,"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/file_type?post=1305"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}