{"id":1101,"date":"2025-04-30T17:11:41","date_gmt":"2025-04-30T17:11:41","guid":{"rendered":"https:\/\/acervolegislativo.com.br\/document\/lei-municipal-no-400-2010-dispoe-sobre-alteracao-de-proprio-publico-emef-luiz-gimenez\/"},"modified":"2025-04-30T17:16:52","modified_gmt":"2025-04-30T17:16:52","slug":"lei-municipal-no-400-2010-dispoe-sobre-alteracao-de-proprio-publico-emef-luiz-gimenez","status":"publish","type":"dlp_document","link":"https:\/\/acervolegislativo.com.br\/pt_br\/document\/lei-municipal-no-400-2010-dispoe-sobre-alteracao-de-proprio-publico-emef-luiz-gimenez\/","title":{"rendered":"Lei Municipal n\u00ba 400 2010   Disp\u00f5e sobre altera\u00e7\u00e3o de Pr\u00f3prio P\u00fablico   Emef Luiz Gimenez."},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":1102,"template":"","doc_categories":[7],"doc_tags":[34],"doc_author":[],"file_type":[11],"class_list":["post-1101","dlp_document","type-dlp_document","status-publish","has-post-thumbnail","hentry","doc_categories-leis-municipais","doc_tags-34","entry","has-media"],"download_url":"https:\/\/acervolegislativo.com.br\/wp-content\/uploads\/2025\/04\/Lei-Municipal-no-400-2010-Dispoe-sobre-alteracao-de-Proprio-Publico-Emef-Luiz-Gimenez.pdf","file_size":"495 KB","filename":"Lei-Municipal-no-400-2010-Dispoe-sobre-alteracao-de-Proprio-Publico-Emef-Luiz-Gimenez.pdf","download_count":"","version_history":[],"_links":{"self":[{"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/dlp_document\/1101","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/dlp_document"}],"about":[{"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/types\/dlp_document"}],"author":[{"embeddable":true,"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/users\/2"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/media\/1102"}],"wp:attachment":[{"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/media?parent=1101"}],"wp:term":[{"taxonomy":"doc_categories","embeddable":true,"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/doc_categories?post=1101"},{"taxonomy":"doc_tags","embeddable":true,"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/doc_tags?post=1101"},{"taxonomy":"doc_author","embeddable":true,"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/doc_author?post=1101"},{"taxonomy":"file_type","embeddable":true,"href":"https:\/\/acervolegislativo.com.br\/pt_br\/wp-json\/wp\/v2\/file_type?post=1101"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}